{"id":78,"count":1,"description":"","link":"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/","name":"Air quality","slug":"air-quality-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Air quality Archive - OTT Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Air quality Archive - OTT Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/\" \/>\n<meta property=\"og:site_name\" content=\"OTT Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/tag\\\/air-quality-en\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/tag\\\/air-quality-en\\\/\",\"name\":\"Air quality Archive - OTT Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/tag\\\/air-quality-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/tag\\\/air-quality-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Air quality\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/\",\"name\":\"OTT Blog\",\"description\":\"HydroMet\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/#organization\",\"name\":\"OTT HydroMet\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"width\":176,\"height\":60,\"caption\":\"OTT HydroMet\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Air quality Archive - OTT Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/","og_locale":"en_US","og_type":"article","og_title":"Air quality Archive - OTT Blog","og_url":"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/","og_site_name":"OTT Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/","url":"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/","name":"Air quality Archive - OTT Blog","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.otthydromet.com\/en\/tag\/air-quality-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.otthydromet.com\/en\/"},{"@type":"ListItem","position":2,"name":"Air quality"}]},{"@type":"WebSite","@id":"https:\/\/blog.otthydromet.com\/en\/#website","url":"https:\/\/blog.otthydromet.com\/en\/","name":"OTT Blog","description":"HydroMet","publisher":{"@id":"https:\/\/blog.otthydromet.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.otthydromet.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.otthydromet.com\/en\/#organization","name":"OTT HydroMet","url":"https:\/\/blog.otthydromet.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.otthydromet.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","width":176,"height":60,"caption":"OTT HydroMet"},"image":{"@id":"https:\/\/blog.otthydromet.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.otthydromet.com\/en\/wp-json\/wp\/v2\/tags\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.otthydromet.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.otthydromet.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.otthydromet.com\/en\/wp-json\/wp\/v2\/posts?tags=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}