{"id":742,"date":"2020-10-08T12:49:08","date_gmt":"2020-10-08T10:49:08","guid":{"rendered":"https:\/\/blogottprod.wpengine.com\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/"},"modified":"2021-01-04T12:27:06","modified_gmt":"2021-01-04T11:27:06","slug":"ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa","status":"publish","type":"post","link":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/","title":{"rendered":"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"742\" class=\"elementor elementor-742 elementor-700\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ab22ed9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ab22ed9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c7a51f7\" data-id=\"1c7a51f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fcf51e8 elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"4fcf51e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Jahr 2020 geht in die Geschichte ein. Nicht nur wegen COVID-19, sondern auch wegen der verheerenden Waldbr\u00e4nde weltweit. Ihre Auswirkungen werden noch lange zu sp\u00fcren sein. Ceilometerdaten aus verschiedenen L\u00e4ndern zeigen, dass sch\u00e4dliche Ru\u00dfpartikel \u00fcber Tausende Kilometer hinweg schweben.<\/p><p>Brennende W\u00e4lder und Buschland haben in Australien, Sibirien und zuletzt in Brasilien und an der Westk\u00fcste der USA Schneisen der Verw\u00fcstung hinterlassen. Eindrucksvolle Satellitenbilder lassen die Ausma\u00dfe der Feuer und des Rauches \u00fcber Kalifornien, Oregon und Washington erkennen. Allerdings sorgen sich die Wissenschaftler nicht nur um die Zerst\u00f6rung der Fl\u00e4chen. Die Flammen setzen gro\u00dfe Mengen Kohlenstoff und anderer Partikel frei. Die meisten davon sind so klein, dass sie mit blo\u00dfem Auge nicht sichtbar sind. Durch ihr geringes Gewicht schweben sie \u00fcber gro\u00dfe Entfernungen hinweg. \u00a0\u00a0<\/p><h3>Lidar-Signale best\u00e4tigen auf Satellitenfotos basierende Simulationen<\/h3><p>Mitte September erreichten die Rauchwolken Europa. Der <a href=\"https:\/\/atmosphere.copernicus.eu\/cams-monitors-smoke-release-devastating-us-wildfires\">Copernicus Atmosphere Monitoring Service (CAMS)<\/a> dessen Aussagen sich auf Satellitenbilder und -simulationen st\u00fctzen, hatte dies bereits vorhergesagt. Wissenschaftler aus verschiedenen L\u00e4ndern haben die Vorhersagen des CAMS nun best\u00e4tigt, auch sie entdeckten den Rauch, der von der Westk\u00fcste kommt. Viele von ihnen verwenden Lidar-Sensoren wie das Lufft CHM 15k &amp; CHM 8k, auch Aaron Kennedy von der University of North Dakota. Er entdeckte Rauchpartikel, die sich \u00fcber Nordamerika Richtung Osten bewegten, bevor sie den Atlantik erreichten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f8cc67 elementor-widget elementor-widget-gallery\" data-id=\"3f8cc67\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:2,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-gallery__titles-container e--pointer-underline e--animation-fade\" aria-label=\"Galeriefilter\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-item elementor-gallery-title\" role=\"button\" tabindex=\"0\" data-gallery-index=\"0\">\n\t\t\t\t\t\tRauchschwaden von der Westk\u00fcste verdunkeln auch in North Dakota den Himmel\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" data-e-gallery-tags=\"0\" href=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/nosmoke.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3f8cc67\" data-elementor-lightbox-title=\"Wildfire smoke impacts air quality hundreds and even thousands of miles away. These two pictures were taken at the University of North Dakota on September 14 (smoke) and 18 (clear sky). Photos: Aaron Kennedy, UND\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzAyLCJ1cmwiOiJodHRwczpcL1wvYmxvZy5vdHRoeWRyb21ldC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzEwXC9ub3Ntb2tlLnBuZyIsInNsaWRlc2hvdyI6IjNmOGNjNjcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/nosmoke-1024x576.png\" data-width=\"800\" data-height=\"450\" aria-label=\"Webcam at University of North Dakota\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" data-e-gallery-tags=\"0\" href=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/smoke.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3f8cc67\" data-elementor-lightbox-title=\"Wildfire smoke impacts air quality hundreds and even thousands of miles away. These two pictures were taken at the University of North Dakota on September 14 (smoke) and 18 (clear sky). Photos: Aaron Kennedy, UND\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzA0LCJ1cmwiOiJodHRwczpcL1wvYmxvZy5vdHRoeWRyb21ldC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzEwXC9zbW9rZS5wbmciLCJzbGlkZXNob3ciOiIzZjhjYzY3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/smoke-1024x576.png\" data-width=\"800\" data-height=\"450\" aria-label=\"Webcam at University of North Dakota\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a825ab5 elementor-widget elementor-widget-text-editor\" data-id=\"a825ab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kennedy arbeitet in der Abteilung f\u00fcr Atmosph\u00e4renwissenschaften der Universit\u00e4t. Ein CHM 15k geh\u00f6rt zu seiner vielseitigen Ausr\u00fcstung. \u201eIn diesem Sommer konnten wir die Rauchwolken zum ersten Mal mit Hilfe von Ceilometern beobachten. W\u00e4hrend der Brandereignisse haben wir die Daten dem \u00f6rtlichen B\u00fcro des Nationalen Wetterdienstes \u00fcbermittelt. So konnte man dort besser einsch\u00e4tzen, wie dicht der Rauch ist und in welcher H\u00f6he sich die Partikel bewegen\u201c, sagt Kennedy.<\/p><h3>Unkontrollierte Br\u00e4nde wirken sich auf Wetter und Luftqualit\u00e4t aus<\/h3><p>Normalerweise ist es die Hauptaufgabe von Ceilometern, die H\u00f6he der Wolkenbasis zu messen. Besonders relevant ist dies f\u00fcr Meteorologen und Flugh\u00e4fen. Dar\u00fcber hinaus sind Ceilometer in der Lage, in der Luft str\u00f6mende winzige Partikel, so genannte Aerosole, zu erfassen. Daher sind sie wichtige Instrumente f\u00fcr Studien \u00fcber Luftverschmutzung und Luftqualit\u00e4t.<\/p><p>Br\u00e4nde sind ein normales Ph\u00e4nomen und treten jedes Jahr auf. In diesem Jahr allerdings w\u00fcten viele Feuer l\u00e4nger und erstrecken sich \u00fcber gr\u00f6\u00dfere Gebiete als gew\u00f6hnlich. Schwere Br\u00e4nde haben Auswirkungen auf die Umwelt und die Atmosph\u00e4re, wie Kennedy erkl\u00e4rt: \u201eZum einen streut der Rauch von Wildbr\u00e4nden die Energie der Sonne und wirkt sich tags\u00fcber k\u00fchlend aus. In den meisten Wettermodellen ist Rauch nicht vorgesehen. Wird er von den Meteorologen nicht ber\u00fccksichtigt, k\u00f6nnen sie daher zu falschen Aussagen f\u00fchren. Obwohl die Rauchfahnen von Wildfeuern sich in der Regel in gr\u00f6\u00dferen H\u00f6hen bewegen, k\u00f6nnen sie sich manchmal mit den tieferen Luftschichten am Boden vermischen. In diesem Fall schadet das der Luftqualit\u00e4t. Zum anderen ver\u00e4ndern sie die visuellen Eigenschaften der Atmosph\u00e4re, was dazu f\u00fchrt, dass Sonnenunterg\u00e4nge intensiver, der Himmel nicht mehr als blau erscheinen.\u201d<\/p><h3>Lidar-Sensoren \u00ad\u2013 sehr vielseitige Messger\u00e4te<\/h3><p>Inzwischen hat die Rauchwolke den Atlantik \u00fcberquert. Kennedys Kollegen <a href=\"https:\/\/alg.umbc.edu\/2020\/09\/16\/hazy-east-smoke\/\">an der Ostk\u00fcste<\/a> und in Europa \u00fcberwachen den Rauch mit Lidaren. Am 11. September berichtete Hugo Ricketts vom Centre for Atmospheric Science an der University of Manchester, er habe \u201eletzte Nacht in ausgew\u00e4hlten L\u00fccken zwischen den Wolken rauchig aussehende Aerosole\u201c beobachtet. Kroatische und deutsche Meteorologen schickten einige Tage sp\u00e4ter Aufnahmen ihrer Ceilometer-Messungen mit dem<br \/>\u00a0CHM 15k.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07c56dc elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"07c56dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"07c56dc\" data-elementor-lightbox-title=\"Rauchschwaden erreichten Capel Dewi\/Wales am 10. September. Die Signale unterhalb der markierten Wolkenschicht deuten auf Rauch.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzE2LCJ1cmwiOiJodHRwczpcL1wvYmxvZy5vdHRoeWRyb21ldC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzEwXC9sdWZmdF9jZGFvX1VLLnBuZyIsInNsaWRlc2hvdyI6IjA3YzU2ZGMifQ%3D%3D\" href=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/lufft_cdao_UK.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/lufft_cdao_UK-1024x512.png\" alt=\"Ceilometer Signal\" \/><figcaption class=\"elementor-image-carousel-caption\">Rauchschwaden erreichten Capel Dewi\/Wales am 10. September. Die Signale unterhalb der markierten Wolkenschicht deuten auf Rauch.<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"07c56dc\" data-elementor-lightbox-title=\"Rauchsignale in Kroatien, aufgenommen am 12. September vom Kroatischen Hydrologischen &amp; Meteorologischen Dienst\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzIyLCJ1cmwiOiJodHRwczpcL1wvYmxvZy5vdHRoeWRyb21ldC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzEwXC9DSE0xNWtfREhNWl9jcm9wLmpwZyIsInNsaWRlc2hvdyI6IjA3YzU2ZGMifQ%3D%3D\" href=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/CHM15k_DHMZ_crop.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/CHM15k_DHMZ_crop.jpg\" alt=\"Ceilometer Signal\" \/><figcaption class=\"elementor-image-carousel-caption\">Rauchsignale in Kroatien, aufgenommen am 12. September vom Kroatischen Hydrologischen &amp; Meteorologischen Dienst<\/figcaption><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 3\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"07c56dc\" data-elementor-lightbox-title=\"Smoke detected at the University of North Dakota on August 23.\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzE4LCJ1cmwiOiJodHRwczpcL1wvYmxvZy5vdHRoeWRyb21ldC5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzEwXC9zbW9rZV8xNFNlcHQyMDIwVU5ELnBuZyIsInNsaWRlc2hvdyI6IjA3YzU2ZGMifQ%3D%3D\" href=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/smoke_14Sept2020UND.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/10\/smoke_14Sept2020UND-1024x492.png\" alt=\"Ceilometer signal\" \/><figcaption class=\"elementor-image-carousel-caption\">Smoke detected at the University of North Dakota on August 23.<\/figcaption><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed4396 elementor-widget elementor-widget-text-editor\" data-id=\"9ed4396\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei Ereignissen wie diesen gro\u00dfen Br\u00e4nden stellen Ceilometer ihre Vielseitigkeit unter Beweis. Aaron Kennedy kombiniert sie sogar mit anderen Messinstrumenten, um einen detaillierteren Einblick in die verschiedenen Ph\u00e4nomene zu erhalten. Kennedy verwendet zum Beispiel einen OTT Parsivel\u00b2, ein Disdrometer, welches die Geschwindigkeit und Gr\u00f6\u00dfe von Partikeln, haupts\u00e4chlich Niederschlag, erfasst. \u201eLidar sind f\u00fcr viele Bereiche n\u00fctzlich\u201c, sagt er, \u201ez.B. hat der Rauch von Wildbr\u00e4nden Auswirkungen auf Faktoren wie Sichtverh\u00e4ltnisse und Luftqualit\u00e4t. Traditionell wurden Ceilometer allerdings nur dazu verwendet, Wolkenh\u00f6hen f\u00fcr die Luftfahrt zu ermitteln. F\u00fcr das Winterwetter liefern sie Informationen dar\u00fcber, in welcher H\u00f6he sich die Flugschneeschicht bewegt. In einigen F\u00e4llen k\u00f6nnen wir diese Beobachtungen mit Radarmessungen kombinieren und daraus sogar Eigenschaften wie die Partikelgr\u00f6\u00dfe absch\u00e4tzen.\u201d<\/p>\n<p>Kennedys Arbeit an der Universit\u00e4t von North Dakota ist beispielhaft f\u00fcr einen weltweiten Trend in der Meteorologie, Klimatologie und Atmosph\u00e4renforschung. Diese Bereiche sind eng miteinander verbunden, und Wissenschaftler untersuchen verst\u00e4rkt, wie sie sich gegenseitig beeinflussen. Die Auswirkungen der diesj\u00e4hrigen Waldbr\u00e4nde zeigen, dass Lidare wie die Lufft-Ceilometer dabei helfen, komplexe Ph\u00e4nomene zu \u00fcberwachen und zu verstehen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c02d86a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c02d86a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26236f8 elementor-widget elementor-widget-text-editor\" data-id=\"26236f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Lesenswert<\/h4><ul><li><a href=\"https:\/\/www.spiegel.de\/wissenschaft\/natur\/rauch-von-us-waldbraenden-zieht-bis-nach-deutschland-a-908c07b2-7210-48e5-a95d-c6bc07d7e24d\">Rauch von US-Waldbr\u00e4nden zieht bis nach Deutschland<\/a> &#8211; SPIEGEL Online<\/li><li><a href=\"https:\/\/graphics.reuters.com\/CALIFORNIA-WILDFIRES\/xegvboxrypq\/index.html\">A Devastated West Coast<\/a> &#8211; Reuters (Englisch)<\/li><li><a href=\"https:\/\/www.bbc.com\/future\/article\/20200821-how-wildfire-pollution-may-be-harming-your-health\">The long distance harm done by wildfires<\/a> &#8211; BBC (Englisch)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Das Jahr 2020 geht in die Geschichte ein. Nicht nur wegen COVID-19, sondern auch wegen der verheerenden Waldbr\u00e4nde weltweit. Ihre Auswirkungen werden noch lange zu sp\u00fcren sein. Ceilometerdaten aus verschiedenen L\u00e4ndern zeigen, dass sch\u00e4dliche Ru\u00dfpartikel \u00fcber Tausende Kilometer hinweg schweben. Brennende W\u00e4lder und Buschland haben in Australien, Sibirien und zuletzt in Brasilien und an der [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[73,72,74,71],"class_list":["post-742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meteorologie","tag-aerosol-2","tag-ceilometer-2","tag-lidar-2","tag-luftqualitaet-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA - OTT Blog<\/title>\n<meta name=\"description\" content=\"2020 ist das Jahr der Waldbr\u00e4nde. Gef\u00e4hrliche Rauchpartikel schweben \u00fcber Tausende von Kilometern, laut internationalen Ceilometermessungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA - OTT Blog\" \/>\n<meta property=\"og:description\" content=\"2020 ist das Jahr der Waldbr\u00e4nde. Gef\u00e4hrliche Rauchpartikel schweben \u00fcber Tausende von Kilometern, laut internationalen Ceilometermessungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"OTT Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-08T10:49:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-04T11:27:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/06\/wildfire.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Martin Maly\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Maly\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/\"},\"author\":{\"name\":\"Martin Maly\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/02f0ad93990b2dbe9fff4654361ec736\"},\"headline\":\"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA\",\"datePublished\":\"2020-10-08T10:49:08+00:00\",\"dateModified\":\"2021-01-04T11:27:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/\"},\"wordCount\":890,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wildfire.png\",\"keywords\":[\"Aerosole\",\"Ceilometer\",\"Lidar\",\"Luftqualit\u00e4t\"],\"articleSection\":[\"Meteorologie\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/\",\"name\":\"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA - OTT Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wildfire.png\",\"datePublished\":\"2020-10-08T10:49:08+00:00\",\"dateModified\":\"2021-01-04T11:27:06+00:00\",\"description\":\"2020 ist das Jahr der Waldbr\u00e4nde. Gef\u00e4hrliche Rauchpartikel schweben \u00fcber Tausende von Kilometern, laut internationalen Ceilometermessungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wildfire.png\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wildfire.png\",\"width\":1000,\"height\":599,\"caption\":\"Waldbr\u00e4nde nahe einer Stadt in Kalifornien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"name\":\"OTT Blog\",\"description\":\"HydroMet\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\",\"name\":\"OTT HydroMet\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"width\":176,\"height\":60,\"caption\":\"OTT HydroMet\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/02f0ad93990b2dbe9fff4654361ec736\",\"name\":\"Martin Maly\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Maly_2025_Pyranometers-150x150.jpg\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Maly_2025_Pyranometers-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Maly_2025_Pyranometers-150x150.jpg\",\"caption\":\"Martin Maly\"},\"description\":\"Physiker. Wissenschaftsautor. Podcaster. Vertriebler. Meine beruflichen Anf\u00e4nge als mehrsprachiger, preisgekr\u00f6nter Sportjournalist lagen in Zeitungsredaktionen und Rundfunk. Nun widme ich mich noch spannenderen Themen wie Technologie, Meteorologie und erneuerbaren Energien. Bei OTT HydroMet betreue ich eine riesige und faszinierende Region, die vom Baltikum bis zum Balkan, von meinem Heimatland Polen bis nach Kasachstan reicht. Ich brenne daf\u00fcr, dort den \u00dcbergang zu einer erneuerbaren Energielandschaft zu unterst\u00fctzen. Zudem liebe ich Sport, Berge und Heavy Metal.\",\"sameAs\":[\"https:\\\/\\\/www.otthydromet.com\\\/\"],\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/author\\\/martinmaly\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA - OTT Blog","description":"2020 ist das Jahr der Waldbr\u00e4nde. Gef\u00e4hrliche Rauchpartikel schweben \u00fcber Tausende von Kilometern, laut internationalen Ceilometermessungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/","og_locale":"de_DE","og_type":"article","og_title":"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA - OTT Blog","og_description":"2020 ist das Jahr der Waldbr\u00e4nde. Gef\u00e4hrliche Rauchpartikel schweben \u00fcber Tausende von Kilometern, laut internationalen Ceilometermessungen.","og_url":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/","og_site_name":"OTT Blog","article_published_time":"2020-10-08T10:49:08+00:00","article_modified_time":"2021-01-04T11:27:06+00:00","og_image":[{"width":1000,"height":599,"url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/06\/wildfire.png","type":"image\/png"}],"author":"Martin Maly","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Martin Maly","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/#article","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/"},"author":{"name":"Martin Maly","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/02f0ad93990b2dbe9fff4654361ec736"},"headline":"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA","datePublished":"2020-10-08T10:49:08+00:00","dateModified":"2021-01-04T11:27:06+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/"},"wordCount":890,"commentCount":0,"publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/06\/wildfire.png","keywords":["Aerosole","Ceilometer","Lidar","Luftqualit\u00e4t"],"articleSection":["Meteorologie"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/","url":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/","name":"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA - OTT Blog","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/#primaryimage"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/06\/wildfire.png","datePublished":"2020-10-08T10:49:08+00:00","dateModified":"2021-01-04T11:27:06+00:00","description":"2020 ist das Jahr der Waldbr\u00e4nde. Gef\u00e4hrliche Rauchpartikel schweben \u00fcber Tausende von Kilometern, laut internationalen Ceilometermessungen.","breadcrumb":{"@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/#primaryimage","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/06\/wildfire.png","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/06\/wildfire.png","width":1000,"height":599,"caption":"Waldbr\u00e4nde nahe einer Stadt in Kalifornien"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.otthydromet.com\/de\/ceilometer-in-europa-erfassen-rauch-von-waldbraenden-aus-den-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.otthydromet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Ceilometer in Europa erfassen Rauch von Waldbr\u00e4nden aus den USA"}]},{"@type":"WebSite","@id":"https:\/\/blog.otthydromet.com\/de\/#website","url":"https:\/\/blog.otthydromet.com\/de\/","name":"OTT Blog","description":"HydroMet","publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.otthydromet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.otthydromet.com\/de\/#organization","name":"OTT HydroMet","url":"https:\/\/blog.otthydromet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","width":176,"height":60,"caption":"OTT HydroMet"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/02f0ad93990b2dbe9fff4654361ec736","name":"Martin Maly","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2025\/04\/Maly_2025_Pyranometers-150x150.jpg","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2025\/04\/Maly_2025_Pyranometers-150x150.jpg","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2025\/04\/Maly_2025_Pyranometers-150x150.jpg","caption":"Martin Maly"},"description":"Physiker. Wissenschaftsautor. Podcaster. Vertriebler. Meine beruflichen Anf\u00e4nge als mehrsprachiger, preisgekr\u00f6nter Sportjournalist lagen in Zeitungsredaktionen und Rundfunk. Nun widme ich mich noch spannenderen Themen wie Technologie, Meteorologie und erneuerbaren Energien. Bei OTT HydroMet betreue ich eine riesige und faszinierende Region, die vom Baltikum bis zum Balkan, von meinem Heimatland Polen bis nach Kasachstan reicht. Ich brenne daf\u00fcr, dort den \u00dcbergang zu einer erneuerbaren Energielandschaft zu unterst\u00fctzen. Zudem liebe ich Sport, Berge und Heavy Metal.","sameAs":["https:\/\/www.otthydromet.com\/"],"url":"https:\/\/blog.otthydromet.com\/de\/author\/martinmaly\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/comments?post=742"}],"version-history":[{"count":0,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/media\/609"}],"wp:attachment":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/media?parent=742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/categories?post=742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/tags?post=742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}