{"id":1013720,"date":"2016-11-28T11:06:45","date_gmt":"2016-11-28T10:06:45","guid":{"rendered":"http:\/\/blog.lufft.com\/?p=13720"},"modified":"2017-09-20T08:38:55","modified_gmt":"2017-09-20T06:38:55","slug":"sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen","status":"publish","type":"post","link":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/","title":{"rendered":"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen"},"content":{"rendered":"<p><span id=\"result_box\" class=\"\" lang=\"de\" tabindex=\"-1\"><span class=\"\">Piloten, Fluglotsen und Flughafenbetreiber setzen alles daran, um den Flugverkehr sicherer und effizienter zu gestalten. <\/span>Manchmal h\u00e4ngt die Flugsicherheit aber von externen Faktoren ab, die wir kaum beeinflussen k\u00f6nnen. <span class=\"\">Hierbei sind vor allem extreme Wetterbedingungen gemeint.<\/span> <span class=\"\">Wie Lufft-Sensoren helfen, mit diesen Einfl\u00fcssen umzugehen, steht im folgenden Beitrag&#8230;<\/span><\/span><\/p>\n<p><!--more--><\/p>\n<p>Piloten, Fluglotsen und Flughafenbetreiber setzen alles daran den Flugverkehr sicherer und effizienter zu gestalten. Manchmal h\u00e4ngt die Flugsicherheit aber von externen Faktoren ab, die wir kaum beeinflussen k\u00f6nnen. Hierbei sind vor allem extreme Wetterbedingungen gemeint: Starke Winde, eisige K\u00e4lte oder auch starke Niederschl\u00e4ge k\u00f6nnen schwerwiegende Folgen mit sich bringen. Im Schnitt lassen sich 23% aller Flugzeugunf\u00e4lle in 2015 und 68% der stornierten Fl\u00fcge auf widrige Wetterbedingungen zur\u00fcckf\u00fchren (Quelle: FAA).<\/p>\n<p>Wie gef\u00e4hrlich die Wetterlage auf Flugh\u00e4fen sein kann, zeigen folgende Beispiele:<\/p>\n<ul>\n<li>Landung der <a href=\"http:\/\/www.nbcnewyork.com\/news\/local\/Plane-Off-Runway-LaGuardia-Airport-New-York-Snow-295187641.html\">MD-88-Delta-Maschine, die im M\u00e4rz 2015 von der Landebahn des LaGuardia, New York Flughafens rutschte und in einen Zaun krachte<\/a><\/li>\n<li>Versuchter Start <a href=\"http:\/\/www.belfasttelegraph.co.uk\/news\/northern-ireland\/belfast-airport-passengers-stranded-after-truck-collides-with-packed-plane-35231454.html\">in Belfast am 21. November 2016, bei dem eine EasyJet ausgerechnet mit einem Winterdienstfahrzeug kollidierte<\/a><\/li>\n<li>Oder die Beispiele aus dem NBC-Video*.<\/li>\n<\/ul>\n<p>NBC-Video*:<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"http:\/\/www.nbcnewyork.com\/portableplayer\/?cmsID=295256171&amp;videoID=kgoM6ySpXXyM&amp;origin=nbcnewyork.com&amp;sec=news&amp;subsec=local&amp;width=600&amp;height=360\" type=\"text\/javascript\" charset=\"UTF-8\"><\/script><\/p>\n<p><em>Quelle: www.NBCNewYork.com<\/em><\/p>\n<p>Abhilfe verschaffen <a href=\"https:\/\/www.airport-suppliers.com\/supplier\/g-lufft-mess-und-regeltechnik\/\">AWOS<\/a> (Automated Airport Weather Stations) ausgestattet mit modernster (Lufft)-Technik, die Flugh\u00e4fen rund um die Uhr \u00fcberwachen.<\/p>\n<p>Station\u00e4re AWOS bestehen aus<\/p>\n<ul>\n<li><a href=\"http:\/\/lufft.com\/en\/products\/road-sensors\/\">eingebauten Runway-Sensoren<\/a> wie dem passiven <a href=\"http:\/\/lufft.com\/en\/products\/produktsuche\/?q=IRS31Pro-UMB\">IRS31Pro-UMB<\/a> in Verbindung mit dem aktiven <a href=\"http:\/\/lufft.com\/en\/products\/road-sensors\/intelligent-active-road-sensor-ars31pro-umb-8810u051\/\">ARS31Pro-UMB<\/a><\/li>\n<li><a href=\"https:\/\/www.lufft.com\/products\/compact-weather-sensors-293\/\">All-in-One Wettersensoren<\/a>, zur Beobachtung von Umgebungstemperaturen, Windst\u00e4rken, Niederschl\u00e4gen, Luft-Feuchte, Luftdruck usw.<\/li>\n<li><a href=\"https:\/\/www.lufft.com\/de-de\/produkte\/wolken-schneehoehensensoren-306\/ceilometer-chm-15k-nimbus-2093\/\">Wolkenh\u00f6hensensoren <\/a><\/li>\n<li>und <a href=\"http:\/\/lufft.com\/de\/produkte\/optische-sensoren\/sichtweitensensor-vs2k-umb-8366u70\/\">Sichtweitensensoren<\/a>.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Neben station\u00e4ren Wetterbeobachtungsanlagen, gibt es inzwischen auch den <a href=\"https:\/\/www.lufft.com\/de-de\/produkte\/strassen-runwaysensoren-308\/marwis-umb-mobiler-strassenwetter-sensor-1797\/\">mobilen Runway-Sensor MARWIS<\/a>, der an einem Fahrzeug montiert in Echtzeit Oberfl\u00e4chenzust\u00e4nde inkl. der Eisanteile und Reibung ausgibt.<\/p>\n\n<p>Alle <a href=\"http:\/\/lufft.com\/en\/products\/\">Lufft-Sensoren<\/a>\u00a0lassen sich dank offenem <a href=\"http:\/\/www.umb-technik.info\/\">UMB-Protokoll<\/a> einfach sowie flexibel in AWOS-Systeme integrieren und sind langzeitwartungsfrei.<\/p>\n<p>Die Messdaten flie\u00dfen in sogenannte MDSS (Maintenance Decision Support System), TALPA\u2019s (Takeoff and Landing Performance Assessment) sowie NOWTAM (Notice To Airmen) ein, mit denen v.a. Starts und Landungen sicherer werden.<\/p>\n<p><span id=\"result_box\" class=\"\" lang=\"de\" tabindex=\"-1\"><span class=\"\">Kharkiv Flughafen in der Ukraine, Flughafen Bergamo in Italien, Frankfurt Hahn Flughafen und Flughafen D\u00fcsseldorf in Deutschland und viele mehr verlassen sich bereits auf Lufft-Sensoren, um gef\u00e4hrliche und teure Vorf\u00e4lle <\/span><\/span><span id=\"result_box\" class=\"\" lang=\"de\" tabindex=\"-1\"><span class=\"\">zu vermeiden.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Sie haben Fragen zu unseren Sensoren? Nehmen Sie am besten gleich Kontakt zu uns auf \u2013 wir beraten Sie gerne!<\/p>\n<p><a href=\"https:\/\/bloglufftprd2.wpengine.com\/kontakt\/\" target=\"_blank\"><img decoding=\"async\" class=\"alignnone wp-image-13785\" src=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2016\/11\/Kontakt-aufnehmen-Button-4.png\" width=\"150\" height=\"34\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piloten, Fluglotsen und Flughafenbetreiber setzen alles daran, um den Flugverkehr sicherer und effizienter zu gestalten. Manchmal h\u00e4ngt die Flugsicherheit aber von externen Faktoren ab, die wir kaum beeinflussen k\u00f6nnen. Hierbei sind vor allem extreme Wetterbedingungen gemeint. Wie Lufft-Sensoren helfen, mit diesen Einfl\u00fcssen umzugehen, steht im folgenden Beitrag&#8230;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,46],"tags":[],"class_list":["post-1013720","post","type-post","status-publish","format-standard","hentry","category-meteorologie","category-meteorology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen - OTT Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen - OTT Blog\" \/>\n<meta property=\"og:description\" content=\"Piloten, Fluglotsen und Flughafenbetreiber setzen alles daran, um den Flugverkehr sicherer und effizienter zu gestalten. Manchmal h\u00e4ngt die Flugsicherheit aber von externen Faktoren ab, die wir kaum beeinflussen k\u00f6nnen. Hierbei sind vor allem extreme Wetterbedingungen gemeint. Wie Lufft-Sensoren helfen, mit diesen Einfl\u00fcssen umzugehen, steht im folgenden Beitrag&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/\" \/>\n<meta property=\"og:site_name\" content=\"OTT Blog\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-28T10:06:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-20T06:38:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2016\/11\/Kontakt-aufnehmen-Button-4.png\" \/>\n<meta name=\"author\" content=\"OTT HydroMet Blog Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"OTT HydroMet Blog Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/\"},\"author\":{\"name\":\"OTT HydroMet Blog Team\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\"},\"headline\":\"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen\",\"datePublished\":\"2016-11-28T10:06:45+00:00\",\"dateModified\":\"2017-09-20T06:38:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/\"},\"wordCount\":392,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Kontakt-aufnehmen-Button-4.png\",\"articleSection\":[\"Meteorologie\",\"Meteorology\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/\",\"name\":\"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen - OTT Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Kontakt-aufnehmen-Button-4.png\",\"datePublished\":\"2016-11-28T10:06:45+00:00\",\"dateModified\":\"2017-09-20T06:38:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Kontakt-aufnehmen-Button-4.png\",\"contentUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Kontakt-aufnehmen-Button-4.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"name\":\"OTT Blog\",\"description\":\"HydroMet\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\",\"name\":\"OTT HydroMet\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"width\":176,\"height\":60,\"caption\":\"OTT HydroMet\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\",\"name\":\"OTT HydroMet Blog Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"caption\":\"OTT HydroMet Blog Team\"},\"description\":\"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.\",\"sameAs\":[\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/\"],\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/author\\\/ott-hydromet-blog-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen - OTT Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/","og_locale":"de_DE","og_type":"article","og_title":"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen - OTT Blog","og_description":"Piloten, Fluglotsen und Flughafenbetreiber setzen alles daran, um den Flugverkehr sicherer und effizienter zu gestalten. Manchmal h\u00e4ngt die Flugsicherheit aber von externen Faktoren ab, die wir kaum beeinflussen k\u00f6nnen. Hierbei sind vor allem extreme Wetterbedingungen gemeint. Wie Lufft-Sensoren helfen, mit diesen Einfl\u00fcssen umzugehen, steht im folgenden Beitrag&#8230;","og_url":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/","og_site_name":"OTT Blog","article_published_time":"2016-11-28T10:06:45+00:00","article_modified_time":"2017-09-20T06:38:55+00:00","og_image":[{"url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2016\/11\/Kontakt-aufnehmen-Button-4.png","type":"","width":"","height":""}],"author":"OTT HydroMet Blog Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"OTT HydroMet Blog Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/#article","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/"},"author":{"name":"OTT HydroMet Blog Team","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd"},"headline":"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen","datePublished":"2016-11-28T10:06:45+00:00","dateModified":"2017-09-20T06:38:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/"},"wordCount":392,"commentCount":0,"publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2016\/11\/Kontakt-aufnehmen-Button-4.png","articleSection":["Meteorologie","Meteorology"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/","url":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/","name":"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen - OTT Blog","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/#primaryimage"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2016\/11\/Kontakt-aufnehmen-Button-4.png","datePublished":"2016-11-28T10:06:45+00:00","dateModified":"2017-09-20T06:38:55+00:00","breadcrumb":{"@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/#primaryimage","url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2016\/11\/Kontakt-aufnehmen-Button-4.png","contentUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2016\/11\/Kontakt-aufnehmen-Button-4.png"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.otthydromet.com\/de\/sichere-landung-bei-jedem-wetter-lufft-sensorik-auf-flughaefen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.otthydromet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Sichere Landung bei jedem Wetter: Lufft-Sensorik auf Flugh\u00e4fen"}]},{"@type":"WebSite","@id":"https:\/\/blog.otthydromet.com\/de\/#website","url":"https:\/\/blog.otthydromet.com\/de\/","name":"OTT Blog","description":"HydroMet","publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.otthydromet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.otthydromet.com\/de\/#organization","name":"OTT HydroMet","url":"https:\/\/blog.otthydromet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","width":176,"height":60,"caption":"OTT HydroMet"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd","name":"OTT HydroMet Blog Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","caption":"OTT HydroMet Blog Team"},"description":"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.","sameAs":["https:\/\/blog.otthydromet.com\/en\/"],"url":"https:\/\/blog.otthydromet.com\/de\/author\/ott-hydromet-blog-team\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1013720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/comments?post=1013720"}],"version-history":[{"count":0,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1013720\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/media?parent=1013720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/categories?post=1013720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/tags?post=1013720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}