{"id":1003779,"date":"2014-04-28T00:00:20","date_gmt":"2014-04-27T22:00:20","guid":{"rendered":"http:\/\/blog.lufft.com\/?p=3779"},"modified":"2017-09-12T14:43:00","modified_gmt":"2017-09-12T12:43:00","slug":"fifa-worldcup-2014-in-brasilien","status":"publish","type":"post","link":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/","title":{"rendered":"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft"},"content":{"rendered":"<p style=\"text-align: left;\">Schon sehr bald beginnen die Spiele um die Fu\u00dfball-Weltmeisterschaft in Brasilien, worauf alle gespannt sein d\u00fcrfen. Doch ein wichtiger Faktor sollte nicht ausser Acht gelassen werden: Das wechselhafte und k\u00f6rperlich belastende Klima des gr\u00f6\u00dften Staates S\u00fcdamerikas. Deshalb sind die Austragungsorte mit Lufft Wetterstationen ausger\u00fcstet und somit bestens auf alle meteorologischen Bedingungen vorbereitet. Mehr dar\u00fcber welche T\u00fccken das brasilianische Klima mit sich bringt und wie diese zu handlen sind, findet Ihr in diesem Blogbeitrag&#8230;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2014\/04\/Stadion-Fotolia-Brasil.jpg\"><!--more--><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-3781\" alt=\"Stadion Fotolia Brasil\" src=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2014\/04\/Stadion-Fotolia-Brasil.jpg\" width=\"689\" height=\"341\" \/><\/a><em><\/em><\/p>\n<p style=\"text-align: center;\"><em>Foto Credit: KB3 &#8211; Fotolia.com<\/em><\/p>\n<p style=\"text-align: justify;\">Es sind nur noch wenige Wochen bis die ersten Spiele der Weltmeisterschaft 2014 ausgetragen werden. An zw\u00f6lf Spielorten werden die besten Fu\u00dfballmannschaften der ganzen Welt aufeinander treffen. Am 16. Juni 2014 bestreitet die Deutsche Nationalmannschaft ihr erstes Match gegen Portugal. In der Gruppe G warten als weitere Konkurrenten Ghana und die USA. Betrachtet man die bisherige Spielbilanz gilt Deutschland als klarer Favorit in dieser Gruppe. Doch neben den spielerischen Leistungen sollte sich die DFB-Elf auch auf einen weiteren wichtigen Faktor vorbereiten: Das wechselhafte und k\u00f6rperlich belastende brasilianische Klima.<\/p>\n<p style=\"text-align: justify;\">Brasilien ist mit 8,5 Millionen Quadratkilometern der gr\u00f6\u00dfte Staat S\u00fcdamerikas. Mit den ausgedehnten Regenw\u00e4ldern des Amazonas im Norden und den Hochebenen sowie Gebirgen im S\u00fcden gelten f\u00fcr dieses Land unterschiedliche klimatische Verh\u00e4ltnisse.\u00a0 Generell herrscht ein tropisches Klima mit extrem hoher Luftfeuchtigkeit. Im Norden gibt es meist reichhaltige Niederschl\u00e4ge wogegen im S\u00fcden h\u00e4ufig Abschnitte mit starker Hitze und Trockenperioden vorkommen. Neben diesen stark ausgepr\u00e4gten Unterschieden gibt es auch in einigen Regionen zahlreiche Mikroklimata. In einem Radius von nur wenigen Kilometern kann es regnen und zugleich die Sonne scheinen.<\/p>\n<p style=\"text-align: justify;\"><b>Was bedeutet das f\u00fcr die kommende Fu\u00dfball-WM?<\/b><\/p>\n<p style=\"text-align: justify;\">Die klimatischen Verh\u00e4ltnisse und das Wetter m\u00fcssen exakt \u00fcberwacht werden. Zuverl\u00e4ssige Prognosen f\u00fcr die Spieltage m\u00fcssen getroffen werden, um die Spieler, Zuschauer aber auch die Brasilianer selbst zu informieren und gegebenenfalls zu sch\u00fctzen. Durch starke Regeng\u00fcsse kann es teilweise zu Erdrutschen kommen, besonders davon betroffen ist die \u00e4rmere Bev\u00f6lkerungsschicht in den Favelas. Diese sind oft an H\u00e4ngen angesiedelt. Nur mit einem \u00dcberwachungssystem, welches in Echtzeit arbeitet, haben zeitnahe Evakuierungen eine Chance. Dazu holte sich die FIFA mit Lufft einen absoluten Klimaexperten nach Brasilien. Alle WM-Spielorte wurden bereits im letzten Jahr mit der Kompaktwetterstation <a title=\"WS301-UMB Produktseite\" href=\"https:\/\/www.lufft.com\/de-de\/produkte\/intelligente-wettersensoren-309\/ws301-umb-intelligente-wettersensorik-2254\/\" target=\"_blank\">WS301-UMB<\/a> ausgestattet und konnten beim FIFA Confederations Cup 2013 einen Testlauf absolvieren.<\/p>\n\n<p style=\"text-align: justify;\">Die Messsensoren zeichnen Temperatur, relative Feuchte, Luftdruck, Globalstrahlung sowie \u00fcber einen externen Sensor die Niederschlagsmenge auf. Nicht nur die Technik ist modern, sondern auch das Design. Die Wetterstationen sind hinter den Toren kaum wahrnehmbar und garantieren somit einen ungest\u00f6rten Fu\u00dfballgenuss.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schon sehr bald beginnen die Spiele um die Fu\u00dfball-Weltmeisterschaft in Brasilien, worauf alle gespannt sein d\u00fcrfen. Doch ein wichtiger Faktor sollte nicht ausser Acht gelassen werden: Das wechselhafte und k\u00f6rperlich belastende Klima des gr\u00f6\u00dften Staates S\u00fcdamerikas. Deshalb sind die Austragungsorte mit Lufft Wetterstationen ausger\u00fcstet und somit bestens auf alle meteorologischen Bedingungen vorbereitet. Mehr dar\u00fcber welche [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,46],"tags":[],"class_list":["post-1003779","post","type-post","status-publish","format-standard","hentry","category-meteorologie","category-meteorology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft - OTT Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft - OTT Blog\" \/>\n<meta property=\"og:description\" content=\"Schon sehr bald beginnen die Spiele um die Fu\u00dfball-Weltmeisterschaft in Brasilien, worauf alle gespannt sein d\u00fcrfen. Doch ein wichtiger Faktor sollte nicht ausser Acht gelassen werden: Das wechselhafte und k\u00f6rperlich belastende Klima des gr\u00f6\u00dften Staates S\u00fcdamerikas. Deshalb sind die Austragungsorte mit Lufft Wetterstationen ausger\u00fcstet und somit bestens auf alle meteorologischen Bedingungen vorbereitet. Mehr dar\u00fcber welche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/\" \/>\n<meta property=\"og:site_name\" content=\"OTT Blog\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-27T22:00:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-12T12:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2014\/04\/Stadion-Fotolia-Brasil.jpg\" \/>\n<meta name=\"author\" content=\"OTT HydroMet Blog Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"OTT HydroMet Blog Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/\"},\"author\":{\"name\":\"OTT HydroMet Blog Team\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\"},\"headline\":\"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft\",\"datePublished\":\"2014-04-27T22:00:20+00:00\",\"dateModified\":\"2017-09-12T12:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/\"},\"wordCount\":449,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Stadion-Fotolia-Brasil.jpg\",\"articleSection\":[\"Meteorologie\",\"Meteorology\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/\",\"name\":\"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft - OTT Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Stadion-Fotolia-Brasil.jpg\",\"datePublished\":\"2014-04-27T22:00:20+00:00\",\"dateModified\":\"2017-09-12T12:43:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Stadion-Fotolia-Brasil.jpg\",\"contentUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Stadion-Fotolia-Brasil.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/fifa-worldcup-2014-in-brasilien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"name\":\"OTT Blog\",\"description\":\"HydroMet\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\",\"name\":\"OTT HydroMet\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"width\":176,\"height\":60,\"caption\":\"OTT HydroMet\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\",\"name\":\"OTT HydroMet Blog Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"caption\":\"OTT HydroMet Blog Team\"},\"description\":\"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.\",\"sameAs\":[\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/\"],\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/author\\\/ott-hydromet-blog-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft - OTT Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/","og_locale":"de_DE","og_type":"article","og_title":"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft - OTT Blog","og_description":"Schon sehr bald beginnen die Spiele um die Fu\u00dfball-Weltmeisterschaft in Brasilien, worauf alle gespannt sein d\u00fcrfen. Doch ein wichtiger Faktor sollte nicht ausser Acht gelassen werden: Das wechselhafte und k\u00f6rperlich belastende Klima des gr\u00f6\u00dften Staates S\u00fcdamerikas. Deshalb sind die Austragungsorte mit Lufft Wetterstationen ausger\u00fcstet und somit bestens auf alle meteorologischen Bedingungen vorbereitet. Mehr dar\u00fcber welche [&hellip;]","og_url":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/","og_site_name":"OTT Blog","article_published_time":"2014-04-27T22:00:20+00:00","article_modified_time":"2017-09-12T12:43:00+00:00","og_image":[{"url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2014\/04\/Stadion-Fotolia-Brasil.jpg","type":"","width":"","height":""}],"author":"OTT HydroMet Blog Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"OTT HydroMet Blog Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/#article","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/"},"author":{"name":"OTT HydroMet Blog Team","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd"},"headline":"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft","datePublished":"2014-04-27T22:00:20+00:00","dateModified":"2017-09-12T12:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/"},"wordCount":449,"commentCount":3,"publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2014\/04\/Stadion-Fotolia-Brasil.jpg","articleSection":["Meteorologie","Meteorology"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/","url":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/","name":"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft - OTT Blog","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/#primaryimage"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2014\/04\/Stadion-Fotolia-Brasil.jpg","datePublished":"2014-04-27T22:00:20+00:00","dateModified":"2017-09-12T12:43:00+00:00","breadcrumb":{"@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/#primaryimage","url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2014\/04\/Stadion-Fotolia-Brasil.jpg","contentUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2014\/04\/Stadion-Fotolia-Brasil.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.otthydromet.com\/de\/fifa-worldcup-2014-in-brasilien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.otthydromet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Der Countdown zum FIFA Worldcup 2014 in Brasilien l\u00e4uft"}]},{"@type":"WebSite","@id":"https:\/\/blog.otthydromet.com\/de\/#website","url":"https:\/\/blog.otthydromet.com\/de\/","name":"OTT Blog","description":"HydroMet","publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.otthydromet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.otthydromet.com\/de\/#organization","name":"OTT HydroMet","url":"https:\/\/blog.otthydromet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","width":176,"height":60,"caption":"OTT HydroMet"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd","name":"OTT HydroMet Blog Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","caption":"OTT HydroMet Blog Team"},"description":"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.","sameAs":["https:\/\/blog.otthydromet.com\/en\/"],"url":"https:\/\/blog.otthydromet.com\/de\/author\/ott-hydromet-blog-team\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1003779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/comments?post=1003779"}],"version-history":[{"count":0,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1003779\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/media?parent=1003779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/categories?post=1003779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/tags?post=1003779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}