{"id":1001597,"date":"2012-10-01T00:00:37","date_gmt":"2012-09-30T22:00:37","guid":{"rendered":"http:\/\/blog.lufft.com\/?p=1597"},"modified":"2017-09-12T14:03:42","modified_gmt":"2017-09-12T12:03:42","slug":"ein-blick-in-die-zukunft","status":"publish","type":"post","link":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/","title":{"rendered":"Ein Blick in die Zukunft"},"content":{"rendered":"<p>Die Kunst des Wahrsagens hat eine weitreichende Geschichte. Nicht zuletzt ging es dabei oft darum, das Wetter vorauszusagen. Umweltkatastrophen wie Orkane oder Erdbeben kosteten schon fr\u00fcher zahlreiche Menschenleben.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/bloglufftprd2.wpengine.com\/ein-blick-in-die-zukunft\/2012_09_wetter-zukunft_lufft\/\" rel=\"attachment wp-att-1598\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1598\" title=\"Wetter - Zukunft - Lufft\" src=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/09\/2012_09_Wetter-Zukunft_Lufft.jpg\" alt=\"\" width=\"698\" height=\"341\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em>(Foto-Credit: wajan &#8211; Fotolia.com)<\/em><\/p>\n<p>Die Kunst des Wahrsagens hat eine weitreichende Geschichte. Schon vor mehreren Jahrtausenden war die Menschheit bestrebt, einen Blick in die Zukunft wagen zu k\u00f6nnen, um kommende Ereignisse voraussagen zu k\u00f6nnen. Wahrsagen ist in allen Gesellschaften und Zeitaltern nachgewiesen, aus denen es Schriftzeugnisse gibt. Bereits 3000 Jahre v. Chr. \u00fcbten sich Menschen in verschiedenen Praktiken, um die g\u00f6ttlichen Hinweise zu interpretieren.<\/p>\n<p>Nicht zuletzt ging es dabei darum, das Wetter vorauszusagen. Umweltkatastrophen wie Orkane oder Erdbeben kosteten schon damals zahlreiche Menschenleben. Flut, Hagel und D\u00fcrreperioden bedrohten die Agrarwirtschaft. F\u00e4llt der Winter eher mild aus oder ist mit starken Minusgraden zu rechnen? Die Umweltbedingungen zu kennen war lebensnotwendig.<\/p>\n<p>Im 21. Jahrhundert hat sich daran wenig ge\u00e4ndert. Noch immer hat das Wetter die Macht, \u00fcber Leben und Tod zu bestimmen und ein heilloses Chaos anzurichten. Hurrikans fliegen \u00fcber das Land und verw\u00fcsten die Gegend. Unwetter verhageln die Ernte. Hochwasser fluten zahlreiche Keller. St\u00fcrme st\u00fcrzen B\u00e4ume auf Stra\u00dfen. Doch eines hat sich ge\u00e4ndert.<\/p>\n<p>Statt auf g\u00f6ttliche Hinweise vertraut der Mensch heutzutage auf modernste Technik. Ger\u00e4te aus dem Bereich der Mess- und Regeltechnik erlauben zuverl\u00e4ssige Prognosen \u00fcber Wetter\u00e4nderungen. Mithilfe der gewonnenen Wetterdaten lassen sich starke Umschw\u00fcnge rechtzeitig antizipieren und die entsprechenden Vorkehrungen treffen, um sich anzupassen und vorzubereiten.<\/p>\n<p>Besonders geeignet daf\u00fcr sind Wetterstationen, die mehrere Daten gleichzeitig ermitteln. Auf diesem Bereich hat sich in den letzten Jahren die <a title=\"Lufft Kompaktwetterstation WS600-UMB\" href=\"https:\/\/www.lufft.com\/products\/compact-weather-sensors-293\/ws600-umb-smart-weather-sensor-1832\/\" target=\"_blank\">Kompaktwetterstation WS600-UMB<\/a> von LUFFT bew\u00e4hrt. Dank zahlreicher Sensoren ist die Station ein echter Allrounder: Sie musst Lufttemperatur und -druck, die relative Feuchte, Niederschlagsintensit\u00e4t, -art und -menge sowie die Windrichtung und -geschwindigkeit.<\/p>\n<p>Starke Umschw\u00fcnge und Wetterbedingungen sind dabei f\u00fcr LUFFT-Produkte kein Problem. Die Messger\u00e4te werden testweise st\u00e4rksten Belastungen ausgesetzt, um auch in Extremsituationen verl\u00e4ssliche Ergebnisse zu liefern. Der <a title=\"Lufft Ultraschall-Windsensor Ventus-UMB\" href=\"https:\/\/www.lufft.com\/de-de\/produkte\/windsensoren-anemometer-307\/ventus-umb-ultraschall-windsensor-1795\/\" target=\"_blank\">Ultraschall-Windsensor Ventus-UMB<\/a> wurde in den letzten Monaten beispielsweise auf dem Schweizer La Dole, einem 1677 Meter hohen Berg, validiert. (<a title=\"Lufft - Ventus-UMB Validationsstudie\" href=\"https:\/\/www.lufft.com\/de-de\/produkte\/windsensoren-anemometer-307\/\" target=\"_blank\">Zur Studie<\/a>) Zudem hat er die UL-Zulassung bestanden, die f\u00fcr den amerikanischen Markt erforderlich ist. Das Produkt wird mit diesem Label ab August ausgeliefert. (<a title=\"Lufft - Ventus-UMB - UL-Zulassung\" href=\"https:\/\/www.lufft.com\/products\/wind-sensors-anemometers-289\/\" target=\"_blank\">Zur UL-Zulassung<\/a>)<\/p>\n<p>\u00dcberraschende Wetterver\u00e4nderungen geh\u00f6ren damit der Vergangenheit an.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kunst des Wahrsagens hat eine weitreichende Geschichte. Nicht zuletzt ging es dabei oft darum, das Wetter vorauszusagen. Umweltkatastrophen wie Orkane oder Erdbeben kosteten schon fr\u00fcher zahlreiche Menschenleben.<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,46],"tags":[],"class_list":["post-1001597","post","type-post","status-publish","format-standard","hentry","category-meteorologie","category-meteorology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Blick in die Zukunft - OTT Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Blick in die Zukunft - OTT Blog\" \/>\n<meta property=\"og:description\" content=\"Die Kunst des Wahrsagens hat eine weitreichende Geschichte. Nicht zuletzt ging es dabei oft darum, das Wetter vorauszusagen. Umweltkatastrophen wie Orkane oder Erdbeben kosteten schon fr\u00fcher zahlreiche Menschenleben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/\" \/>\n<meta property=\"og:site_name\" content=\"OTT Blog\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-30T22:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-12T12:03:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/09\/2012_09_Wetter-Zukunft_Lufft.jpg\" \/>\n<meta name=\"author\" content=\"OTT HydroMet Blog Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"OTT HydroMet Blog Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/\"},\"author\":{\"name\":\"OTT HydroMet Blog Team\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\"},\"headline\":\"Ein Blick in die Zukunft\",\"datePublished\":\"2012-09-30T22:00:37+00:00\",\"dateModified\":\"2017-09-12T12:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/2012_09_Wetter-Zukunft_Lufft.jpg\",\"articleSection\":[\"Meteorologie\",\"Meteorology\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/\",\"name\":\"Ein Blick in die Zukunft - OTT Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/2012_09_Wetter-Zukunft_Lufft.jpg\",\"datePublished\":\"2012-09-30T22:00:37+00:00\",\"dateModified\":\"2017-09-12T12:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/2012_09_Wetter-Zukunft_Lufft.jpg\",\"contentUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/2012_09_Wetter-Zukunft_Lufft.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/ein-blick-in-die-zukunft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Blick in die Zukunft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"name\":\"OTT Blog\",\"description\":\"HydroMet\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\",\"name\":\"OTT HydroMet\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"width\":176,\"height\":60,\"caption\":\"OTT HydroMet\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\",\"name\":\"OTT HydroMet Blog Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"caption\":\"OTT HydroMet Blog Team\"},\"description\":\"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.\",\"sameAs\":[\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/\"],\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/author\\\/ott-hydromet-blog-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Blick in die Zukunft - OTT Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/","og_locale":"de_DE","og_type":"article","og_title":"Ein Blick in die Zukunft - OTT Blog","og_description":"Die Kunst des Wahrsagens hat eine weitreichende Geschichte. Nicht zuletzt ging es dabei oft darum, das Wetter vorauszusagen. Umweltkatastrophen wie Orkane oder Erdbeben kosteten schon fr\u00fcher zahlreiche Menschenleben.","og_url":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/","og_site_name":"OTT Blog","article_published_time":"2012-09-30T22:00:37+00:00","article_modified_time":"2017-09-12T12:03:42+00:00","og_image":[{"url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/09\/2012_09_Wetter-Zukunft_Lufft.jpg","type":"","width":"","height":""}],"author":"OTT HydroMet Blog Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"OTT HydroMet Blog Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/#article","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/"},"author":{"name":"OTT HydroMet Blog Team","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd"},"headline":"Ein Blick in die Zukunft","datePublished":"2012-09-30T22:00:37+00:00","dateModified":"2017-09-12T12:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/09\/2012_09_Wetter-Zukunft_Lufft.jpg","articleSection":["Meteorologie","Meteorology"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/","url":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/","name":"Ein Blick in die Zukunft - OTT Blog","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/#primaryimage"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/09\/2012_09_Wetter-Zukunft_Lufft.jpg","datePublished":"2012-09-30T22:00:37+00:00","dateModified":"2017-09-12T12:03:42+00:00","breadcrumb":{"@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/#primaryimage","url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/09\/2012_09_Wetter-Zukunft_Lufft.jpg","contentUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/09\/2012_09_Wetter-Zukunft_Lufft.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.otthydromet.com\/de\/ein-blick-in-die-zukunft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.otthydromet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Ein Blick in die Zukunft"}]},{"@type":"WebSite","@id":"https:\/\/blog.otthydromet.com\/de\/#website","url":"https:\/\/blog.otthydromet.com\/de\/","name":"OTT Blog","description":"HydroMet","publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.otthydromet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.otthydromet.com\/de\/#organization","name":"OTT HydroMet","url":"https:\/\/blog.otthydromet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","width":176,"height":60,"caption":"OTT HydroMet"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd","name":"OTT HydroMet Blog Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","caption":"OTT HydroMet Blog Team"},"description":"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.","sameAs":["https:\/\/blog.otthydromet.com\/en\/"],"url":"https:\/\/blog.otthydromet.com\/de\/author\/ott-hydromet-blog-team\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1001597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/comments?post=1001597"}],"version-history":[{"count":0,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1001597\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/media?parent=1001597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/categories?post=1001597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/tags?post=1001597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}