{"id":1001509,"date":"2012-09-03T00:00:02","date_gmt":"2012-09-02T22:00:02","guid":{"rendered":"http:\/\/blog.lufft.com\/?p=1509"},"modified":"2017-09-12T09:33:24","modified_gmt":"2017-09-12T07:33:24","slug":"die-geschichte-der-sauna","status":"publish","type":"post","link":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/","title":{"rendered":"Die Geschichte der Sauna"},"content":{"rendered":"<p>Die Geschichte der Sauna reicht weit zur\u00fcck. Bereits in der Steinzeit kannten die Menschen Saunen. Allerdings handelte es sich damals noch um Erdl\u00f6cher, die mit hei\u00dfen Steinen erw\u00e4rmt wurden, auf die man Wasser goss.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/bloglufftprd2.wpengine.com\/die-geschichte-der-sauna\/2012-08_lufft_sauna\/\" rel=\"attachment wp-att-1510\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1510\" title=\"Sauna\" src=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/08\/2012-08_Lufft_Sauna.jpg\" alt=\"Lufft - Sauna\" width=\"698\" height=\"341\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em>Foto-Credit: anselme von Fotolia.com<\/em><\/p>\n<p>Auch wenn die meisten Menschen die Sauna heute zumeist mit Finnland in Verbindung bringen: Aus Finnland stammt die Sauna nicht. Wohl aber das Wort \u201eSauna\u201c, was soviel wie \u201eRaum aus Holz\u201c bedeutet.<\/p>\n<p>Die Geschichte der Sauna reicht weit zur\u00fcck. Bereits in der Steinzeit kannten die Menschen Saunen. Allerdings handelte es sich damals noch um Erdl\u00f6cher, die mit hei\u00dfen Steinen erw\u00e4rmt wurden, auf die man Wasser goss.<\/p>\n<p>Das Saunieren, \u00e4hnlich wie wir es kennen, wurde in der Antike erfunden. Herodot beschrieb die skythische Gewohnheit, sich nach einer Totenbestattung durch Schwitzen in einem Zelt, das mit gl\u00fchenden Steinen erhitzt wurde, zu reinigen.<\/p>\n<p>Mindestens genauso interessant wie die Geschichte der Sauna ist ihre Wirkung. Beim Saunieren wirken im Wechsel Warm- und Kaltreize auf den K\u00f6rper. Die starke W\u00e4rme in der Sauna veranlasst den K\u00f6rper zur Erweiterung der Blutgef\u00e4\u00dfe in der Haut und zu kr\u00e4ftigem Schwitzen. Dies hat den gleichen Effekt wie Fieber: Der K\u00f6rper reagiert mit der Bildung von Abwehrstoffen gegen Infekte und der Schwei\u00df transportiert Giftstoffe und Schlacken aus dem K\u00f6rper. Die Abk\u00fchlphase senkt die erh\u00f6hten K\u00f6rpertemperaturen wieder auf die Ausgangswerte.<\/p>\n<p>Eine besondere Bedeutung kommt der Luftfeuchtigkeit in der Saunakabine zu, da die Luft nicht zu trocken, aber auch nicht zu feucht sein sollte. Die richtige Luftfeuchtigkeit ist wichtig f\u00fcr Ihr Wohlempfinden und Ihre Gesundheit. Bei zu niedriger Luftfeuchtigkeit werden Ihre Schleimh\u00e4ute in den Atemwegen austrocknen und Sie werden relativ rasch ein Jucken in der Nase oder einen Hustenreiz versp\u00fcren. Ist die Luftfeuchtigkeit jedoch zu hoch, sprich ist viel Wasserdampf in der Luft, wird die K\u00fchlung Ihres K\u00f6rpers \u00fcber die Haut behindert.<\/p>\n<p>W\u00e4hrend die Temperatur vom Boden einer Saunakabine bis hin zur Decke zunimmt, verh\u00e4lt es sich mit der Luftfeuchtigkeit genau umgekehrt: Sie nimmt von der Decke bis hin zum Boden zu. Warum das so ist, ist schnell erkl\u00e4rt: Die frische Luft kommt aus der L\u00fcftungs\u00f6ffnung unter der T\u00fcr in der N\u00e4he des Saunaofens. Durch den Ofen wird die Luft stark erhitzt und steigt zur Decke, wobei sie Feuchtigkeit (vom Aufguss oder vom verdunsteten Schwei\u00df) aufnimmt. Sobald die Luft ges\u00e4ttigt ist, wird sie schwer und sinkt zu Boden. \u00dcber die zweite L\u00fcftungs\u00f6ffnung an der R\u00fcckwand unter den Saunab\u00e4nken kann die Luft entweichen. Durch diese Luftzirkulation herrscht in der Saunakabine an der Decke eine Luftfeuchtigkeit von zwei bis f\u00fcnf Prozent, auf der Bank drei bis zehn Prozent und am Boden zwanzig bis sechzig Prozent. W\u00e4hrend der Dauer eines Aufgusses steigen diese Werte noch etwas an.<\/p>\n<p>Je genauer man die Luftfeuchtigkeit im Raum bestimmen kann, desto besser kann man auch bestimmen, wo man in der Sauna am besten sitzen oder liegen sollte. Lufft bietet eine Reihe von pr\u00e4zisen <a title=\"Lufft Sauna-Hygrometer\" href=\"https:\/\/www.lufft.com\/products\/in-room-measurements-291\/\" target=\"_blank\">Hygrometern<\/a> und <a title=\"Lufft Sauna-Klimamesser\" href=\"https:\/\/www.lufft.com\/products\/in-room-measurements-291\/\" target=\"_blank\">Klimamessern<\/a>, die genaue Auskunft \u00fcber die Luftfeuchtigkeit in der Sauna geben und so helfen, jeden Saunagang noch komfortabler zu machen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Geschichte der Sauna reicht weit zur\u00fcck. Bereits in der Steinzeit kannten die Menschen Saunen. Allerdings handelte es sich damals noch um Erdl\u00f6cher, die mit hei\u00dfen Steinen erw\u00e4rmt wurden, auf die man Wasser goss.<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,46],"tags":[],"class_list":["post-1001509","post","type-post","status-publish","format-standard","hentry","category-meteorologie","category-meteorology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Geschichte der Sauna - OTT Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Geschichte der Sauna - OTT Blog\" \/>\n<meta property=\"og:description\" content=\"Die Geschichte der Sauna reicht weit zur\u00fcck. Bereits in der Steinzeit kannten die Menschen Saunen. Allerdings handelte es sich damals noch um Erdl\u00f6cher, die mit hei\u00dfen Steinen erw\u00e4rmt wurden, auf die man Wasser goss.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/\" \/>\n<meta property=\"og:site_name\" content=\"OTT Blog\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-02T22:00:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-12T07:33:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/08\/2012-08_Lufft_Sauna.jpg\" \/>\n<meta name=\"author\" content=\"OTT HydroMet Blog Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"OTT HydroMet Blog Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/\"},\"author\":{\"name\":\"OTT HydroMet Blog Team\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\"},\"headline\":\"Die Geschichte der Sauna\",\"datePublished\":\"2012-09-02T22:00:02+00:00\",\"dateModified\":\"2017-09-12T07:33:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/\"},\"wordCount\":538,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/2012-08_Lufft_Sauna.jpg\",\"articleSection\":[\"Meteorologie\",\"Meteorology\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/\",\"name\":\"Die Geschichte der Sauna - OTT Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/2012-08_Lufft_Sauna.jpg\",\"datePublished\":\"2012-09-02T22:00:02+00:00\",\"dateModified\":\"2017-09-12T07:33:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/2012-08_Lufft_Sauna.jpg\",\"contentUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/2012-08_Lufft_Sauna.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/die-geschichte-der-sauna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Geschichte der Sauna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"name\":\"OTT Blog\",\"description\":\"HydroMet\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\",\"name\":\"OTT HydroMet\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"width\":176,\"height\":60,\"caption\":\"OTT HydroMet\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\",\"name\":\"OTT HydroMet Blog Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"caption\":\"OTT HydroMet Blog Team\"},\"description\":\"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.\",\"sameAs\":[\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/\"],\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/author\\\/ott-hydromet-blog-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Geschichte der Sauna - OTT Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/","og_locale":"de_DE","og_type":"article","og_title":"Die Geschichte der Sauna - OTT Blog","og_description":"Die Geschichte der Sauna reicht weit zur\u00fcck. Bereits in der Steinzeit kannten die Menschen Saunen. Allerdings handelte es sich damals noch um Erdl\u00f6cher, die mit hei\u00dfen Steinen erw\u00e4rmt wurden, auf die man Wasser goss.","og_url":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/","og_site_name":"OTT Blog","article_published_time":"2012-09-02T22:00:02+00:00","article_modified_time":"2017-09-12T07:33:24+00:00","og_image":[{"url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/08\/2012-08_Lufft_Sauna.jpg","type":"","width":"","height":""}],"author":"OTT HydroMet Blog Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"OTT HydroMet Blog Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/#article","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/"},"author":{"name":"OTT HydroMet Blog Team","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd"},"headline":"Die Geschichte der Sauna","datePublished":"2012-09-02T22:00:02+00:00","dateModified":"2017-09-12T07:33:24+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/"},"wordCount":538,"commentCount":0,"publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/08\/2012-08_Lufft_Sauna.jpg","articleSection":["Meteorologie","Meteorology"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/","url":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/","name":"Die Geschichte der Sauna - OTT Blog","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/#primaryimage"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/08\/2012-08_Lufft_Sauna.jpg","datePublished":"2012-09-02T22:00:02+00:00","dateModified":"2017-09-12T07:33:24+00:00","breadcrumb":{"@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/#primaryimage","url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/08\/2012-08_Lufft_Sauna.jpg","contentUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/08\/2012-08_Lufft_Sauna.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.otthydromet.com\/de\/die-geschichte-der-sauna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.otthydromet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Geschichte der Sauna"}]},{"@type":"WebSite","@id":"https:\/\/blog.otthydromet.com\/de\/#website","url":"https:\/\/blog.otthydromet.com\/de\/","name":"OTT Blog","description":"HydroMet","publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.otthydromet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.otthydromet.com\/de\/#organization","name":"OTT HydroMet","url":"https:\/\/blog.otthydromet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","width":176,"height":60,"caption":"OTT HydroMet"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd","name":"OTT HydroMet Blog Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","caption":"OTT HydroMet Blog Team"},"description":"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.","sameAs":["https:\/\/blog.otthydromet.com\/en\/"],"url":"https:\/\/blog.otthydromet.com\/de\/author\/ott-hydromet-blog-team\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1001509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/comments?post=1001509"}],"version-history":[{"count":0,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1001509\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/media?parent=1001509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/categories?post=1001509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/tags?post=1001509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}