{"id":1001071,"date":"2012-06-01T00:00:55","date_gmt":"2012-05-31T22:00:55","guid":{"rendered":"http:\/\/blog.lufft.com\/?p=1071"},"modified":"2017-09-11T15:38:19","modified_gmt":"2017-09-11T13:38:19","slug":"der-landwirt-und-die-messtechnik","status":"publish","type":"post","link":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/","title":{"rendered":"Der Landwirt und die Messtechnik"},"content":{"rendered":"<p style=\"text-align: left;\">Wetter\u00fcberwachung zur Steigerung der landwirtschaftlichen Ertr\u00e4ge ist nichts Neues mehr. Allerdings entwickelt sich die Messtechnik st\u00e4ndig weiter, so dass innovative Landwirte immerzu Ausschau nach dem h\u00f6chsten Stand der Technik halten, um deren Gewinnspanne mit Hilfe einer pr\u00e4zisen Wetter\u00fcberwachung zu erh\u00f6hen.<\/p>\n<p style=\"text-align: left;\"><!--more--><a href=\"https:\/\/bloglufftprd2.wpengine.com\/der-landwirt-und-die-messtechnik\/agrarmeteorologie_lufft\/\" rel=\"attachment wp-att-1072\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1072\" title=\"Agrarmeteorologie by Lufft\" src=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/05\/Agrarmeteorologie_Lufft.jpg\" alt=\"Agrarmeteorologie\" width=\"698\" height=\"341\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em>Foto-Credit: ferkelraggae von Fotolia.com<\/em><\/p>\n<p style=\"text-align: left;\">Wetter\u00fcberwachung zur Steigerung der landwirtschaftlichen Ertr\u00e4ge ist nichts Neues mehr. Allerdings entwickelt sich die Messtechnik st\u00e4ndig weiter, so dass innovative Landwirte immerzu Ausschau nach dem h\u00f6chsten Stand der Technik halten, um deren Gewinnspanne mit Hilfe einer pr\u00e4zisen Wetter\u00fcberwachung zu erh\u00f6hen.<\/p>\n<p style=\"text-align: left;\"><strong>Joe Lord &#8211; Der Landwirt und Entwickler<\/strong><\/p>\n<p style=\"text-align: left;\">Ein gutes Beispiel ist der Landwirt Joe Lord aus Wisconsin (USA) der ein System zur Vernetzung einiger Wetterstationen mit drahtlosen Funksendern f\u00fcr den Einsatz in seinen Moosbeer-Feldern entwarf und einsetzt. Das System sollte Ihm dabei helfen, die Bew\u00e4sserung der Pflanzen zu optimieren. Seine Anwendung brachte Ihm gro\u00dfen Erfolg \u2013 Indessen haben einige weitere Landwirte seine Anlagen auf deren Anbaugebiete installiert und profitieren mit einer effizienteren Bew\u00e4sserung von h\u00f6heren Gewinnmarschen.<\/p>\n<p style=\"text-align: left;\"><strong>Der Anbau von Moosbeeren und welche Rolle die Messtechnik dabei spielt<\/strong><\/p>\n<p style=\"text-align: left;\">Moosbeeren (engl. Cranberry) wachsen in trockenen Beeten, etwa 1 Meter tief. Die Pflanzen sind immergr\u00fcn, d.h. sie bleiben selbst durch den Winter gr\u00fcn und produzieren mehrere Jahre lang ihre Beeren. Gerade im Fr\u00fchling m\u00fcssen die Spr\u00f6sslinge unbedingt mechanisch bew\u00e4ssert werden. Dies ist ein entscheidender Prozess zur Erntesteigerung. Das System-Design verwendet die <a title=\"WS600-UMB Kompaktwetterstation\" href=\"https:\/\/www.lufft.com\/products\/compact-weather-sensors-293\/ws600-umb-smart-weather-sensor-1832\/\" target=\"_blank\">WS600-UMB Kompaktwetterstation<\/a> zur Messung der Regenmenge und Intensit\u00e4t, Windgeschwindigkeit und Windrichtung, Taupunkt und nat\u00fcrlich zur st\u00e4ndigen \u00dcberwachung der Temperatur. Die t\u00e4gliche, monatliche und j\u00e4hrliche Niederschlagsmenge wird in einer \u00dcberwachungs-Software gespeichert und angezeigt. Diese Daten werden zusammen mit vielen weiteren N\u00e4sse-Sensoren in den vielen Feldern mit Moosbeeren verwendet, um eine pr\u00e4zise Bew\u00e4sserung zu erm\u00f6glichen. Die Messung der Niederschlagsintensit\u00e4t ist zudem sehr hilfreich bei der Entscheidung, wie viel Wasser ein Erzeuger w\u00e4hrend andauerndem Regen hinzuf\u00fcgen sollte.<br \/>\nEin weiterer Mehrwert der WS600-UMB bietet den Landwirten die Messung der Windgeschwindigkeit und -richtung. Bestimmte Insekten-Arten, welche die Moosbeeren bevorzugen, m\u00fcssen chemikalisch kontrolliert werden. Ebenso werden D\u00fcngemittel benutzt, um eine gute Ernte zu garantieren. Die Windgeschwindigkeit und-richtung ist ein entscheidender Parameter zur Bestimmung wann und wie viel Chemie anzuwenden ist.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/bloglufftprd2.wpengine.com\/der-landwirt-und-die-messtechnik\/ev_mt_usa_ws600-solar_2\/\" rel=\"attachment wp-att-1077\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-1077\" title=\"Agrarmeteorologie - USA - Wisconsin - WS600-UMB\" src=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/06\/EV_MT_USA_WS600-solar_2-393x698.jpg\" alt=\"Agrarmeteorologie - USA - Wisconsin - WS600-UMB\" width=\"393\" height=\"698\" \/><\/a><em><\/em><\/p>\n<p style=\"text-align: center;\"><em>Eine der vielen Messstationen mit der Wetterstation WS600-UMB\u00a0 des Landwirts Joe Lord in Wisconsin (USA)<\/em><\/p>\n<p style=\"text-align: left;\">Der Taupunkt ist ein besonders wichtiger Messwert beim Anbau der Moosbeeren. Diese sind sehr empfindlich gegen Frost und m\u00fcssen besonders gesch\u00fctzt werden! Die sandigen Fl\u00e4chen, in denen die Pflanzen angebaut werden, speichern zudem nur sehr schlecht die \u00fcber den Tag aufgenommene W\u00e4rme. Daher werden die Pflanzen bei Gefahr von Gefriertemperatur mit warmem Wasser befeuchtet. Um auch dieser Gegebenheit effizient gegensteuern zu k\u00f6nnen, ist eine starke Vernetzung vieler Temperatursensoren im Anbaugebiet unverzichtbar. Eine hohe Dichte an Messstationen erm\u00f6glicht zudem die automatisierte Steuerung der Bew\u00e4sserungsanlagen.<\/p>\n<p style=\"text-align: left;\"><strong>Lufft als Systempartner und Sensorlieferant<\/strong><\/p>\n<p style=\"text-align: left;\">Nach Meinung des System-Entwicklers ist die WS-Familie von Lufft perfekt geeignet f\u00fcr diese Art von Anwendung. Er bevorzugt die Lufft WS-Familie unter anderem wegen der einfachen Installation und der Modbus-RTU-Schnittstelle, mit der problemlos eine drahtlose Verbindung zum Gesamtsystem hergestellt werden kann. Joe Lord war es bei der Entwicklung des Systems zudem wichtig, dass die Sensoren sehr robust sind und m\u00f6glichst viele Jahre deren Dienst in den Feldern leisten. Bisher wurde er nicht entt\u00e4uscht!<\/p>\n<p>Einige der verschiedenen Projekte, bei denen dieses System zum Einsatz kommt, k\u00f6nnen unter\u00a0 <a title=\"Lord Electric Control\" href=\"http:\/\/www.lordelectriccontrol.com\" target=\"_blank\">www.lordelectriccontrol.com<\/a> betrachtet werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wetter\u00fcberwachung zur Steigerung der landwirtschaftlichen Ertr\u00e4ge ist nichts Neues mehr. Allerdings entwickelt sich die Messtechnik st\u00e4ndig weiter, so dass innovative Landwirte immerzu Ausschau nach dem h\u00f6chsten Stand der Technik halten, um deren Gewinnspanne mit Hilfe einer pr\u00e4zisen Wetter\u00fcberwachung zu erh\u00f6hen.<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,46],"tags":[],"class_list":["post-1001071","post","type-post","status-publish","format-standard","hentry","category-meteorologie","category-meteorology"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Landwirt und die Messtechnik - OTT Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Landwirt und die Messtechnik - OTT Blog\" \/>\n<meta property=\"og:description\" content=\"Wetter\u00fcberwachung zur Steigerung der landwirtschaftlichen Ertr\u00e4ge ist nichts Neues mehr. Allerdings entwickelt sich die Messtechnik st\u00e4ndig weiter, so dass innovative Landwirte immerzu Ausschau nach dem h\u00f6chsten Stand der Technik halten, um deren Gewinnspanne mit Hilfe einer pr\u00e4zisen Wetter\u00fcberwachung zu erh\u00f6hen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/\" \/>\n<meta property=\"og:site_name\" content=\"OTT Blog\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-31T22:00:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-11T13:38:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/05\/Agrarmeteorologie_Lufft.jpg\" \/>\n<meta name=\"author\" content=\"OTT HydroMet Blog Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"OTT HydroMet Blog Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/\"},\"author\":{\"name\":\"OTT HydroMet Blog Team\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\"},\"headline\":\"Der Landwirt und die Messtechnik\",\"datePublished\":\"2012-05-31T22:00:55+00:00\",\"dateModified\":\"2017-09-11T13:38:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/\"},\"wordCount\":598,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/Agrarmeteorologie_Lufft.jpg\",\"articleSection\":[\"Meteorologie\",\"Meteorology\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/\",\"name\":\"Der Landwirt und die Messtechnik - OTT Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/Agrarmeteorologie_Lufft.jpg\",\"datePublished\":\"2012-05-31T22:00:55+00:00\",\"dateModified\":\"2017-09-11T13:38:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/Agrarmeteorologie_Lufft.jpg\",\"contentUrl\":\"https:\\\/\\\/blogottprod.wpengine.com\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/Agrarmeteorologie_Lufft.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/der-landwirt-und-die-messtechnik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Landwirt und die Messtechnik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"name\":\"OTT Blog\",\"description\":\"HydroMet\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#organization\",\"name\":\"OTT HydroMet\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ottblog_logo.svg\",\"width\":176,\"height\":60,\"caption\":\"OTT HydroMet\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/#\\\/schema\\\/person\\\/af95a261e2bd0d6e87f32548016cbddd\",\"name\":\"OTT HydroMet Blog Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"contentUrl\":\"https:\\\/\\\/blog.otthydromet.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/OTT_HydroMet_icon_512x512-150x150.png\",\"caption\":\"OTT HydroMet Blog Team\"},\"description\":\"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.\",\"sameAs\":[\"https:\\\/\\\/blog.otthydromet.com\\\/en\\\/\"],\"url\":\"https:\\\/\\\/blog.otthydromet.com\\\/de\\\/author\\\/ott-hydromet-blog-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Landwirt und die Messtechnik - OTT Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/","og_locale":"de_DE","og_type":"article","og_title":"Der Landwirt und die Messtechnik - OTT Blog","og_description":"Wetter\u00fcberwachung zur Steigerung der landwirtschaftlichen Ertr\u00e4ge ist nichts Neues mehr. Allerdings entwickelt sich die Messtechnik st\u00e4ndig weiter, so dass innovative Landwirte immerzu Ausschau nach dem h\u00f6chsten Stand der Technik halten, um deren Gewinnspanne mit Hilfe einer pr\u00e4zisen Wetter\u00fcberwachung zu erh\u00f6hen.","og_url":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/","og_site_name":"OTT Blog","article_published_time":"2012-05-31T22:00:55+00:00","article_modified_time":"2017-09-11T13:38:19+00:00","og_image":[{"url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/05\/Agrarmeteorologie_Lufft.jpg","type":"","width":"","height":""}],"author":"OTT HydroMet Blog Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"OTT HydroMet Blog Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/#article","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/"},"author":{"name":"OTT HydroMet Blog Team","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd"},"headline":"Der Landwirt und die Messtechnik","datePublished":"2012-05-31T22:00:55+00:00","dateModified":"2017-09-11T13:38:19+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/"},"wordCount":598,"commentCount":0,"publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/05\/Agrarmeteorologie_Lufft.jpg","articleSection":["Meteorologie","Meteorology"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/","url":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/","name":"Der Landwirt und die Messtechnik - OTT Blog","isPartOf":{"@id":"https:\/\/blog.otthydromet.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/#primaryimage"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/#primaryimage"},"thumbnailUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/05\/Agrarmeteorologie_Lufft.jpg","datePublished":"2012-05-31T22:00:55+00:00","dateModified":"2017-09-11T13:38:19+00:00","breadcrumb":{"@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/#primaryimage","url":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/05\/Agrarmeteorologie_Lufft.jpg","contentUrl":"https:\/\/blogottprod.wpengine.com\/wp-content\/uploads\/2012\/05\/Agrarmeteorologie_Lufft.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.otthydromet.com\/de\/der-landwirt-und-die-messtechnik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.otthydromet.com\/de\/"},{"@type":"ListItem","position":2,"name":"Der Landwirt und die Messtechnik"}]},{"@type":"WebSite","@id":"https:\/\/blog.otthydromet.com\/de\/#website","url":"https:\/\/blog.otthydromet.com\/de\/","name":"OTT Blog","description":"HydroMet","publisher":{"@id":"https:\/\/blog.otthydromet.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.otthydromet.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.otthydromet.com\/de\/#organization","name":"OTT HydroMet","url":"https:\/\/blog.otthydromet.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/07\/ottblog_logo.svg","width":176,"height":60,"caption":"OTT HydroMet"},"image":{"@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.otthydromet.com\/de\/#\/schema\/person\/af95a261e2bd0d6e87f32548016cbddd","name":"OTT HydroMet Blog Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","url":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","contentUrl":"https:\/\/blog.otthydromet.com\/wp-content\/uploads\/2020\/02\/OTT_HydroMet_icon_512x512-150x150.png","caption":"OTT HydroMet Blog Team"},"description":"Observing the elements is key to better understanding our planet. This blog tells the manifold stories of experts working in environmental monitoring with help of our sensors and solutions.","sameAs":["https:\/\/blog.otthydromet.com\/en\/"],"url":"https:\/\/blog.otthydromet.com\/de\/author\/ott-hydromet-blog-team\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1001071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/comments?post=1001071"}],"version-history":[{"count":0,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/posts\/1001071\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/media?parent=1001071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/categories?post=1001071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.otthydromet.com\/de\/wp-json\/wp\/v2\/tags?post=1001071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}